{"id":1109,"date":"2025-05-09T09:04:23","date_gmt":"2025-05-09T12:04:23","guid":{"rendered":"https:\/\/www.apostilasopcao.com.br\/blog\/?p=1109"},"modified":"2025-05-13T11:31:13","modified_gmt":"2025-05-13T14:31:13","slug":"prefeitura-goias","status":"publish","type":"post","link":"https:\/\/www.apostilasopcao.com.br\/blog\/prefeitura-goias\/","title":{"rendered":"Concurso Prefeitura de Goi\u00e1s: Edital publicado com 479 vagas!"},"content":{"rendered":"\n<p>Est\u00e1 buscando uma oportunidade no servi\u00e7o p\u00fablico com estabilidade e bons sal\u00e1rios? O <a href=\"https:\/\/www.apostilasopcao.com.br\/concurso\/prefeitura-municipal-de-goias-go\">Concurso Prefeitura de Goi\u00e1s<\/a> acaba de divulgar seu edital com um total de <strong>479 vagas<\/strong>, sendo 79 para provimento imediato e 400 para cadastro reserva. As oportunidades abrangem os <strong>n\u00edveis m\u00e9dio, t\u00e9cnico e superior<\/strong>, oferecendo a chance de ingressar em uma carreira s\u00f3lida no setor p\u00fablico. Confira todos os detalhes!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Resumo do edital<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Vagas:<\/strong> 79 imediatas + 400 CR<\/li>\n\n\n\n<li><strong>Inscri\u00e7\u00f5es:<\/strong> 09\/06\/2025 a 07\/07\/2025<\/li>\n\n\n\n<li><strong>Taxa de Inscri\u00e7\u00e3o:<\/strong> R$90 a R$120<\/li>\n\n\n\n<li><strong>Prova:<\/strong> 24\/08\/2025<\/li>\n\n\n\n<li><strong>Banca Organizadora:<\/strong> Itame Concursos<\/li>\n\n\n\n<li><a href=\"https:\/\/www.apostilasopcao.com.br\/blog\/wp-content\/uploads\/2025\/05\/edital-goias.pdf\">Baixe o edital <\/a><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Inscri\u00e7\u00f5es do concurso Prefeitura de Goi\u00e1s<\/h2>\n\n\n\n<p>Os interessados em participar do concurso Prefeitura de Goi\u00e1s poder\u00e3o se inscrever exclusivamente pelo site da banca organizadora, o <a href=\"https:\/\/www.itame.com.br\/site\/concursos.aspx\" target=\"_blank\" rel=\"noreferrer noopener\">Instituto Itame Concursos,<\/a> entre os dias <strong>9 de junho<\/strong> e <strong>7 de julho de 2025<\/strong>.<\/p>\n\n\n\n<p>Para que a inscri\u00e7\u00e3o seja devidamente homologada, ser\u00e1 necess\u00e1rio preencher o formul\u00e1rio eletr\u00f4nico no site da banca e efetuar o pagamento da taxa correspondente ao n\u00edvel do cargo pretendido, conforme os valores abaixo:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>N\u00edvel m\u00e9dio\/t\u00e9cnico<\/strong>: R$90,00<\/li>\n\n\n\n<li><strong>N\u00edvel superior<\/strong>: R$120,00<\/li>\n<\/ul>\n\n\n\n<p>\u00c9 importante que o candidato realize o pagamento at\u00e9 o dia <strong>10 de julho.<\/strong><\/p>\n\n\n\n<p>Ter\u00e1 direito \u00e0 isen\u00e7\u00e3o o candidato de baixa renda, inscrito no Cad\u00danico, conforme o Decreto Federal n\u00ba 11.016\/2022. O pedido deve ser feito entre os dias <strong>9 <\/strong>e <strong>15 de junho<\/strong>, no site da banca.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Cargos e vagas do concurso Prefeitura de Goi\u00e1s<\/h2>\n\n\n\n<p>O concurso Prefeitura de Goi\u00e1s oferece cargos variados para candidatos com diferentes n\u00edveis de escolaridade. Confira as oportunidades:<\/p>\n\n\n\n<p><strong>N\u00edvel m\u00e9dio\/t\u00e9cnico<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.apostilasopcao.com.br\/apostila\/prefeitura-goias-go-agente-apoio-escolar\">Agente de Apoio Escolar:<\/a> 30 vagas + 150 CR \u2013 R$ 1.680,00<\/li>\n\n\n\n<li>Agente Fiscal de Obras, Posturas, Ambiental, Tr\u00e2nsito, Transportes, do Consumidor e outros servi\u00e7os: 3 vagas + 15 CR \u2013 R$ 2.275,72<\/li>\n\n\n\n<li>Agente Fiscal de Tributos: 3 vagas + 15 CR \u2013 R$ 2.275,72<\/li>\n\n\n\n<li>Agente Fiscal Sanit\u00e1rio: 5 CR \u2013 R$ 2.275,72<\/li>\n\n\n\n<li><a href=\"https:\/\/www.apostilasopcao.com.br\/apostila\/prefeitura-goias-go-tecnico-enfermagem\">T\u00e9cnico em Enfermagem:<\/a> 11 vagas + 55 CR \u2013 R$ 1.821,60<\/li>\n<\/ul>\n\n\n\n<p><strong>N\u00edvel superior<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Enfermeiro: 2 vagas + 10 CR \u2013 R$ 3.155,67<\/li>\n\n\n\n<li>Professor P-III: 30 vagas + 150 CR \u2013 R$ 3.016,22<\/li>\n<\/ul>\n\n\n\n<p>A carga hor\u00e1ria semanal ser\u00e1 de 30 horas para o cargo de Agente de Apoio Escolar e 40 horas para os demais cargos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Requisitos do concurso Prefeitura de Goi\u00e1s<\/h2>\n\n\n\n<p>Os candidatos devem atender aos requisitos espec\u00edficos de cada fun\u00e7\u00e3o. Confira abaixo:<\/p>\n\n\n\n<p><strong>Agente de Apoio Escolar<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Ensino m\u00e9dio completo.<\/li>\n<\/ul>\n\n\n\n<p><strong>Agente Fiscal de Obras, Posturas, Ambiental, Tr\u00e2nsito e Transportes, do Consumidor e outros servi\u00e7os<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Ensino m\u00e9dio completo;<\/li>\n\n\n\n<li>Aptid\u00e3o f\u00edsica e mental compat\u00edvel com as atribui\u00e7\u00f5es do cargo.<\/li>\n<\/ul>\n\n\n\n<p><strong>Agente Fiscal de Tributos<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Ensino m\u00e9dio completo;<\/li>\n\n\n\n<li>Aptid\u00e3o f\u00edsica e mental compat\u00edvel com as atribui\u00e7\u00f5es do cargo.<\/li>\n<\/ul>\n\n\n\n<p><strong>Agente Fiscal Sanit\u00e1rio<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Ensino m\u00e9dio completo;<\/li>\n\n\n\n<li>Aptid\u00e3o f\u00edsica e mental compat\u00edvel com as atribui\u00e7\u00f5es do cargo.<\/li>\n<\/ul>\n\n\n\n<p><strong>T\u00e9cnico em Enfermagem<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Curso t\u00e9cnico em Enfermagem, com reconhecimento oficial;<\/li>\n\n\n\n<li>Registro ativo no respectivo conselho de classe.<\/li>\n<\/ul>\n\n\n\n<p><strong>Enfermeiro<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Gradua\u00e7\u00e3o completa em Enfermagem, com reconhecimento oficial;<\/li>\n\n\n\n<li>Registro ativo no respectivo conselho de classe.<\/li>\n<\/ul>\n\n\n\n<p><strong>Professor P-III<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Gradua\u00e7\u00e3o completa em Pedagogia, em institui\u00e7\u00e3o reconhecida pelos \u00f3rg\u00e3os competentes.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Etapas de sele\u00e7\u00e3o<\/h2>\n\n\n\n<p>O concurso Prefeitura de Goi\u00e1s ser\u00e1 composto por duas etapas:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Prova objetiva (eliminat\u00f3ria e classificat\u00f3ria) para todos os cargos;<\/li>\n\n\n\n<li>Prova de t\u00edtulos (classificat\u00f3ria) exclusiva para o cargo de Professor P-III.<\/li>\n<\/ul>\n\n\n\n<p>As provas objetivas est\u00e3o previstas para o dia <strong>24 de agosto de 2025<\/strong> (domingo). No entanto, caso haja grande n\u00famero de inscritos, poder\u00e3o tamb\u00e9m ser aplicadas no dia <strong>23 de agosto de 2025 <\/strong>(s\u00e1bado), conforme divulgado posteriormente em edital. As avalia\u00e7\u00f5es ocorrer\u00e3o, preferencialmente, no munic\u00edpio de Goi\u00e1s\/GO.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Prova objetiva<\/h3>\n\n\n\n<p>A prova ser\u00e1 composta por quest\u00f5es de m\u00faltipla escolha, com 4 alternativas e apenas uma correta. A estrutura varia conforme o n\u00edvel de escolaridade:<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"652\" height=\"365\" src=\"https:\/\/www.apostilasopcao.com.br\/blog\/wp-content\/uploads\/2025\/05\/disciplinas.webp\" alt=\"Disciplinas do concurso Prefeitura de Goi\u00e1s!\" class=\"wp-image-1113\" srcset=\"https:\/\/www.apostilasopcao.com.br\/blog\/wp-content\/uploads\/2025\/05\/disciplinas.webp 652w, https:\/\/www.apostilasopcao.com.br\/blog\/wp-content\/uploads\/2025\/05\/disciplinas-300x168.webp 300w\" sizes=\"auto, (max-width: 652px) 100vw, 652px\" \/><figcaption class=\"wp-element-caption\"><em>Disciplinas da prova objetiva do concurso Prefeitura de Goi\u00e1s!<\/em><\/figcaption><\/figure>\n\n\n\n<p>A prova objetiva ter\u00e1 valor m\u00e1ximo de 60 pontos. Para ser aprovado nessa etapa, o candidato dever\u00e1 alcan\u00e7ar, no m\u00ednimo:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>20 pontos, se concorrer a cargos de n\u00edvel m\u00e9dio;<\/li>\n\n\n\n<li>30 pontos, se concorrer a cargos de n\u00edvel superior.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Prova de t\u00edtulos<\/h3>\n\n\n\n<p>Candidatos para o cargo de Professor P-III aprovados e classificados na prova objetiva, poder\u00e3o participar da etapa de prova de t\u00edtulos, que ser\u00e1 exclusivamente classificat\u00f3ria.<\/p>\n\n\n\n<p>Os documentos dever\u00e3o ser enviados entre os dias <strong>18 e 24 de setembro de 2025<\/strong>. A pontua\u00e7\u00e3o m\u00e1xima ser\u00e1 de 6,0 pontos, conforme a forma\u00e7\u00e3o acad\u00eamica:<\/p>\n\n\n\n<figure class=\"wp-block-table aligncenter\" style=\"font-size:15px\"><table class=\"has-fixed-layout\"><thead><tr><th>T\u00edtulo<\/th><th>Pontos<\/th><\/tr><\/thead><tbody><tr><td>Doutorado na \u00e1rea do cargo (com hist\u00f3rico escolar)<\/td><td>3,0<\/td><\/tr><tr><td>Mestrado na \u00e1rea do cargo (com hist\u00f3rico escolar)<\/td><td>2,0<\/td><\/tr><tr><td>P\u00f3s-gradua\u00e7\u00e3o lato sensu na \u00e1rea do cargo (m\u00ednimo 360h, com hist\u00f3rico escolar)<\/td><td>1,0<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Dica Op\u00e7\u00e3o<\/h2>\n\n\n\n<p>Se voc\u00ea quer ser aprovado no concurso Prefeitura de Goi\u00e1s, essa \u00e9 a sua oportunidade para o sucesso! Conte com materiais de qualidade para te ajudarem em sua prepara\u00e7\u00e3o e comece hoje a se preparar para o cargo que ir\u00e1 mudar a sua vida!<\/p>\n\n\n\n<p>Confira:\u00a0<a href=\"https:\/\/www.apostilasopcao.com.br\/apostila\/prefeitura-goias-go-agente-apoio-escolar\">Apostila Prefeitura de Goi\u00e1s &#8211; GO 2025 &#8211; Agente de Apoio Escolar<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Concurso Prefeitura de Goi\u00e1s oferece 479 vagas!<\/p>\n","protected":false},"author":5,"featured_media":1114,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"breadcrumbs_single_post":"","page_title_panel":"","breadcrumbs_single_page":"","single_page_alignment":"","single_page_margin":"","page_structure_type":"","content_style_source":"","content_style":"","blog_post_streched_ed":"","blog_page_streched_ed":"","has_transparent_header":"","disable_transparent_header":"","vertical_spacing_source":"","content_area_spacing":"","single_post_content_background":"","single_page_content_background":"","single_post_boxed_content_spacing":"","single_page_boxed_content_spacing":"","single_post_content_boxed_radius":"","single_page_content_boxed_radius":"","disable_featured_image":"","disable_post_tags":"","disable_author_box":"","disable_posts_navigation":"","disable_comments":"","disable_related_posts":"","disable_header":"","disable_footer":"","footnotes":""},"categories":[4,14],"tags":[166],"class_list":["post-1109","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-go","tag-concurso-prefeitura-de-goias","rishi-post"],"acf":{"data_prova":"20250824","status":"aberto"},"_links":{"self":[{"href":"https:\/\/www.apostilasopcao.com.br\/blog\/wp-json\/wp\/v2\/posts\/1109","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.apostilasopcao.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.apostilasopcao.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.apostilasopcao.com.br\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.apostilasopcao.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1109"}],"version-history":[{"count":2,"href":"https:\/\/www.apostilasopcao.com.br\/blog\/wp-json\/wp\/v2\/posts\/1109\/revisions"}],"predecessor-version":[{"id":1260,"href":"https:\/\/www.apostilasopcao.com.br\/blog\/wp-json\/wp\/v2\/posts\/1109\/revisions\/1260"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.apostilasopcao.com.br\/blog\/wp-json\/wp\/v2\/media\/1114"}],"wp:attachment":[{"href":"https:\/\/www.apostilasopcao.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1109"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.apostilasopcao.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1109"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.apostilasopcao.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1109"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}